{"id":2072,"date":"2026-07-13T18:07:00","date_gmt":"2026-07-13T16:07:00","guid":{"rendered":"https:\/\/www.radioribelle.it\/?p=2072"},"modified":"2026-07-13T10:19:11","modified_gmt":"2026-07-13T08:19:11","slug":"sparse-plus-festival-al-via-dal-16-luglio-il-terzo-tour-in-toscana-2","status":"publish","type":"post","link":"https:\/\/www.radioribelle.it\/index.php\/2026\/07\/13\/sparse-plus-festival-al-via-dal-16-luglio-il-terzo-tour-in-toscana-2\/","title":{"rendered":"Sparse Plus Festival: al via dal 16 luglio il terzo tour in Toscana"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan-681x1024.jpg\" alt=\"\" class=\"wp-image-2073\" width=\"198\" height=\"298\" srcset=\"https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan-681x1024.jpg 681w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan-199x300.jpg 199w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan-768x1155.jpg 768w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan-1021x1536.jpg 1021w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan-1362x2048.jpg 1362w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan-619x931.jpg 619w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/07\/credit-to-Csaba-Meszaros-1-2023-Ordogkatlan.jpg 1689w\" sizes=\"(max-width: 198px) 100vw, 198px\" \/><\/figure><\/div>\n\n\n\n<p><em>Parte da Monteaperti (Castelnuovo Berardenga) l\u2019edizione 2026 del progetto europeo che far\u00e0 tappa anche a Lustignano di Pomarance, Bibbiena, Reggello e Bagnone<\/em> Parte\u00a0gioved\u00ec 16 luglio\u00a0(ore 21:15) da\u00a0Monteaperti\u00a0di\u00a0Castelnuovo Berardenga, il terzo tour in Toscana dello\u00a0<em>Sparse Plus Festival<\/em>, il progetto europeo nato per promuovere lo spettacolo dal vivo professionale nelle aree rurali europee.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p> Il festival far\u00e0 tappa anche a\u00a0<a>Lustignano di Pomarance,\u00a0Bibbiena,\u00a0Reggello\u00a0e\u00a0Bagnone.<\/a> Giunto quest\u2019anno alla terza edizione,\u00a0<em>Sparse Plus Festival<\/em>\u00a0porter\u00e0\u00a0fino al 20 luglio, a\u00a0ingresso gratuito,\u00a0in cinque borghi toscani, lo spettacolo di circo contemporaneo\u00a0<em>ALL IN FLAMES<\/em>,dedicato ai pi\u00f9 piccoli e alle famiglie. Direttamente dall\u2019Ungheria, una coinvolgente performance di giocoleria con il fuoco in stile \u201cspettacolo di strada\u201d, arricchita da un raffinato senso dell\u2019umorismo. Giganteschi attrezzi infuocati, spettacolari elementi pirotecnici e virtuosismi di giocoleria e acrobazie per un\u2019esperienza indimenticabile.<\/p>\n\n\n\n<p>Il programma <em>ALL IN FLAMES\u00a0<\/em>andr\u00e0 in scena\u00a0gioved\u00ec 16 luglio\u00a0(ore 21:15)alla pista di pattinaggio a\u00a0Monteaperti\u00a0di\u00a0Castelnuovo Berardenga\u00a0(SI).\u00a0 Venerd\u00ec 17 luglio\u00a0(ore 21:30) lo spettacolo arriver\u00e0 nella piazza di\u00a0Lustignano\u00a0a\u00a0Pomarance\u00a0(PI).\u00a0Sabato 18 luglio\u00a0(ore 18:00)sar\u00e0 la volta di\u00a0Bibbiena\u00a0(AR), dove\u00a0<em>ALL IN FLAMES\u00a0<\/em>sar\u00e0 ospitato in piazza Tarlati. La performance raggiunger\u00e0 piazza IV Novembre a\u00a0Reggello\u00a0(FI)\u00a0domenica 19 luglio\u00a0(ore 19:30). L\u2019ultimo appuntamento con\u00a0<em>ALL IN FLAMES<\/em>\u00a0\u00e8 in programma\u00a0luned\u00ec 20 luglio\u00a0(ore 21:00) in piazza Monsignor Rosa a\u00a0Bagnone\u00a0(MS).<\/p>\n\n\n\n<p>ALL IN FLAMES Il perch\u00e9 di Sparse Plus<\/p>\n\n\n\n<p>Secondo le statistiche il 30% della popolazione europea vive in aree rurali che hanno meno opportunit\u00e0 di accesso e fruizione culturale. Una mancanza che inevitabilmente si riverbera nel tessuto sociale locale in termini qualitativi, di welfare culturale e quantitativi. Il sistema di \u2018rural touring\u2019 si basa sull\u2019idea di offrire alle comunit\u00e0 rurali e semi-rurali la fruizione di spettacoli per permettere alle comunit\u00e0 di incontrarsi e socializzare in spazi che non sempre vengono utilizzati per ospitare eventi dal vivo e soprattutto di entrare in contatto con esperienze artistiche di qualit\u00e0, spesso fruibili solo in citt\u00e0 pi\u00f9 grandi.<\/p>\n\n\n\n<p>Finanziato dal programma\u00a0Europa Creativa, il progetto\u00a0Sparse Plus\u00a0&#8211; che per l\u2019Italia vede insieme i Circuiti Regionali Multidisciplinari di Marche (AMAT), in qualit\u00e0 di capofila, e Toscana (Fondazione Toscana Spettacolo) &#8211; rappresenta una importantissima risorsa economica per promuovere lo spettacolo dal vivo professionale nelle aree rurali europee.\u00a0A luglio 2026\u00a0il terzo tuor italiano entra nel vivo con\u00a0<em>Sparse Plus festival<\/em>, che attende il pubblico negli splendidi borghi di Marche e Toscana con spettacoli di prosa, danza e circo contemporaneo. Accanto ad AMAT, ente capofila, e Fondazione Toscana Spettacolo gli altri soggetti europei promotori di Sparse plus (<a rel=\"noreferrer noopener\" href=\"http:\/\/www.sparse.eu\/\" target=\"_blank\">www.sparse.eu<\/a>) sono Eesti Tantsuagentuur (Estonia), Fish Eye (Lituania), Shoshin Theatre (Romania), Riksteatern Varmland (Svezia), ed altri aggiunti per la nuova edizione del progetto come Pro Progressione e SINUM (Ungheria), Nova-Sit (Repubblica Ceca), Teatro 4Garoupas (Germania), Art Fraction (Polonia).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parte da Monteaperti (Castelnuovo Berardenga) l\u2019edizione 2026 del progetto europeo che far\u00e0 tappa anche a Lustignano di Pomarance, Bibbiena, Reggello e Bagnone Parte\u00a0gioved\u00ec 16 luglio\u00a0(ore 21:15) da\u00a0Monteaperti\u00a0di\u00a0Castelnuovo Berardenga, il terzo tour in Toscana dello\u00a0Sparse Plus Festival, il progetto europeo nato per promuovere lo spettacolo dal vivo professionale nelle aree rurali europee.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts\/2072"}],"collection":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/comments?post=2072"}],"version-history":[{"count":1,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts\/2072\/revisions"}],"predecessor-version":[{"id":2074,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts\/2072\/revisions\/2074"}],"wp:attachment":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/media?parent=2072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/categories?post=2072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/tags?post=2072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}