{"id":25,"date":"2026-05-13T14:10:00","date_gmt":"2026-05-13T12:10:00","guid":{"rendered":"https:\/\/www.radioribelle.it\/?p=25"},"modified":"2026-05-13T14:37:42","modified_gmt":"2026-05-13T12:37:42","slug":"novita-citta-di-castello-pallavolo-vince-il-titolo-regionale-under-13-maschile-3x3-dellumbria","status":"publish","type":"post","link":"https:\/\/www.radioribelle.it\/index.php\/2026\/05\/13\/novita-citta-di-castello-pallavolo-vince-il-titolo-regionale-under-13-maschile-3x3-dellumbria\/","title":{"rendered":"NOVIT\u00c0 CITTA DI CASTELLO PALLAVOLO VINCE IL TITOLO REGIONALE UNDER 13 MASCHILE 3X3 DELL&#8217;UMBRIA\u00a0"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/05\/4a9022ce-7bf6-49af-a637-05f13d15e26a-1024x1024.jpeg\" alt=\"\" class=\"wp-image-26\" width=\"239\" height=\"239\" srcset=\"https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/05\/4a9022ce-7bf6-49af-a637-05f13d15e26a-1024x1024.jpeg 1024w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/05\/4a9022ce-7bf6-49af-a637-05f13d15e26a-300x300.jpeg 300w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/05\/4a9022ce-7bf6-49af-a637-05f13d15e26a-150x150.jpeg 150w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/05\/4a9022ce-7bf6-49af-a637-05f13d15e26a-768x768.jpeg 768w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/05\/4a9022ce-7bf6-49af-a637-05f13d15e26a-619x619.jpeg 619w, https:\/\/www.radioribelle.it\/wp-content\/uploads\/2026\/05\/4a9022ce-7bf6-49af-a637-05f13d15e26a.jpeg 1254w\" sizes=\"(max-width: 239px) 100vw, 239px\" \/><\/figure><\/div>\n\n\n\n<p>Una giornata indimenticabile quella vissuta Domenica 11 Giugno 2026 presso Il Palazzetto dello Sport &#8221; Domenico Guiducci &#8221; di Deruta dai ragazzi delle squadre\u00a0 del Citt\u00e0 di Castello Pallavolo under 13\/M 3&#215;3\u00a0 e under 12\/M\u00a0 guidate dai tecnici Raffaella Ranieri e Michetti Gabriele.\u00a0<\/p>\n\n\n\n<!--more-->\n\n\n\n<p> La prima a scendere in campo \u00e8 stata la squadra under 13 3&#215;3 maschile che nella semifinale ha avuto la meglio\u00a0 0\/2 sulla Strike Team Monteluce Perugia. Nella finale si affrontavano la\u00a0 Sir Mericat Gialla ed il\u00a0 Citt\u00e0 di Castello Pallavolo. La\u00a0 formazione biancorossa giocava la sua\u00a0 migliore pallavolo,\u00a0 al cospetto dei forti avversari che durante la stagione avevano sempre avuto la meglio sul team biancorosso di Raffaella\u00a0Ranieri , conquistando meritatamente la vittoria 0\/2\u00a0 13\/15\u00a0 12\/15\u00a0 ed il titolo di Campioni Regionali under 13\/M 3&#215;3 dell&#8217;Umbria , di fatto l&#8217;unico titolo regionale maschile che non \u00e8 andato ad appannaggio dal settore giovanile\u00a0targato Sir Mericat.\u00a0 Nella finale under 12 si sono affrontati i\u00a0 pari et\u00e0 della Sir Mericat Reed e del Citt\u00e0 di Castello\u00a0Pallavolo. Questa volta ad avere la meglio 2\/0 era la squadra guidata dal tecnico Andrea\u00a0 con i ragazzi\u00a0Tifernati che conquistavano\u00a0 comunque\u00a0una medaglia d&#8217;argento, insperata ed impensata solo alcuni mesi fa, che ha fatto la felicit\u00e0 di questo gruppo composto per la gran parte da nuovi ragazzi al primo anno di pallavolo.\u00a0Risultati che premiano il lavoro della societ\u00e0 biancorosso e dei tecnici che in questi 3 anni, dalla nuova ripartenza, hanno saputo creare le condizioni di questi importanti risultati. La risposta migliore del Citt\u00e0 di Castello Pallavolo a coloro che\u00a0 la scorsa estate parlavano di una\u00a0 Alta Valle del Tevere &#8221; da alcuni\u00a0 lustri non vince un titolo regionale &#8221;\u00a0 la risposta migliore di un territorio, di una societ\u00e0, dei suoi\u00a0 tecnici e dei ragazzi\u00a0 sul campo come sempre.\u00a0<br>Questi i ragazzi protagonisti di questa cavalcata meravigliosa al Titolo Regionale Under 13\/M 3X3\u00a0 Barbafina, Belli, Epi, Camilleri Biocchini,\u00a0Grilli, Pieroni, Venturini, Zaganelli.<br>Questi i ragazzi che hanno conquistato una inaspettata\u00a0 piazza d&#8217;onore nel Campionato regionale Under 12\/M\u00a0 Barbafina, \u00a0Belloni,\u00a0 Bellucci,\u00a0 Braganti, Maggini, Magnanelli, Lucaccioni, Paoloni, Sensi, Silvestrini.\u00a0 Allenatori Raffaella Ranieri e Gabriele Michetti , Dirigenti Armando\u00a0\u00a0Grazi\u00a0 e\u00a0Matteo Mancini.\u00a0<br>La stagione giovanile del Citt\u00e0 di Castello Pallavolo proseguir\u00e0 con il Volley Camp 2026, aperto a\u00a0 tutti, oltre al lavoro pomeridiano in palestra con il\u00a0 tecnico Andrea Radici.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una giornata indimenticabile quella vissuta Domenica 11 Giugno 2026 presso Il Palazzetto dello Sport &#8221; Domenico Guiducci &#8221; di Deruta dai ragazzi delle squadre\u00a0 del Citt\u00e0 di Castello Pallavolo under 13\/M 3&#215;3\u00a0 e under 12\/M\u00a0 guidate dai tecnici Raffaella Ranieri e Michetti Gabriele.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts\/25"}],"collection":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":1,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"predecessor-version":[{"id":27,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/posts\/25\/revisions\/27"}],"wp:attachment":[{"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radioribelle.it\/index.php\/wp-json\/wp\/v2\/tags?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}